{"id":234165,"date":"2023-12-25T11:33:23","date_gmt":"2023-12-25T11:33:23","guid":{"rendered":"https:\/\/marsys-trans.com\/?page_id=234165"},"modified":"2025-03-17T15:30:48","modified_gmt":"2025-03-17T15:30:48","slug":"nos-valeurs","status":"publish","type":"page","link":"https:\/\/marsys-trans.com\/index.php\/nos-valeurs\/","title":{"rendered":"Nos valeurs"},"content":{"rendered":"<p>[et_pb_section fb_built=\u00a0\u00bb1&Prime; admin_label=\u00a0\u00bbHeader\u00a0\u00bb _builder_version=\u00a0\u00bb4.23.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_enable_color=\u00a0\u00bboff\u00a0\u00bb use_background_color_gradient=\u00a0\u00bbon\u00a0\u00bb background_color_gradient_stops=\u00a0\u00bbrgba(16,31,79,0.4) 75%|gcid-512fcc6d-fb29-46f9-b53e-275a3a6aef53 100%\u00a0\u00bb background_color_gradient_overlays_image=\u00a0\u00bbon\u00a0\u00bb background_image=\u00a0\u00bbhttps:\/\/marsys-trans.com\/wp-content\/uploads\/2023\/12\/Truck-Footer-Logo.jpg\u00a0\u00bb custom_padding=\u00a0\u00bb14vw||8vw||false|false\u00a0\u00bb use_background_color_gradient_tablet=\u00a0\u00bboff\u00a0\u00bb background_color_gradient_stops_tablet=\u00a0\u00bb#2b87da 0%|#29c4a9 0%\u00a0\u00bb background_color_gradient_start_position_tablet=\u00a0\u00bb0%\u00a0\u00bb background_color_gradient_end_position_tablet=\u00a0\u00bb0%\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{%22gcid-512fcc6d-fb29-46f9-b53e-275a3a6aef53%22:%91%22background_color%22,%22background_color_gradient_stops%22%93}\u00a0\u00bb][et_pb_row make_equal=\u00a0\u00bbon\u00a0\u00bb _builder_version=\u00a0\u00bb4.23.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_enable_color=\u00a0\u00bboff\u00a0\u00bb width=\u00a0\u00bb61%\u00a0\u00bb width_tablet=\u00a0\u00bb30%\u00a0\u00bb width_phone=\u00a0\u00bb50%\u00a0\u00bb width_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb module_alignment=\u00a0\u00bbleft\u00a0\u00bb custom_margin=\u00a0\u00bb|||8px|false|false\u00a0\u00bb custom_padding=\u00a0\u00bb|0px||83px|false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.23.4&Prime; _module_preset=\u00a0\u00bbd72c0383-6487-4f2c-ac5c-7d48a6376757&Prime; header_font=\u00a0\u00bb|700|||||||\u00a0\u00bb header_text_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb header_font_size=\u00a0\u00bb5em\u00a0\u00bb header_line_height=\u00a0\u00bb1.1em\u00a0\u00bb z_index=\u00a0\u00bb1&Prime; max_width=\u00a0\u00bb650px\u00a0\u00bb custom_margin=\u00a0\u00bb||10px||false|false\u00a0\u00bb custom_margin_tablet=\u00a0\u00bb|0%|||false|false\u00a0\u00bb custom_margin_phone=\u00a0\u00bb|0%|||false|false\u00a0\u00bb custom_margin_last_edited=\u00a0\u00bboff|desktop\u00a0\u00bb header_text_color_tablet=\u00a0\u00bb#FFFFFF\u00a0\u00bb header_text_color_phone=\u00a0\u00bb#FFFFFF\u00a0\u00bb header_text_color_last_edited=\u00a0\u00bboff|desktop\u00a0\u00bb header_font_size_tablet=\u00a0\u00bb40px\u00a0\u00bb header_font_size_phone=\u00a0\u00bb24px\u00a0\u00bb header_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h1>Nos Valeurs,<\/h1>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.23.4&Prime; _module_preset=\u00a0\u00bb1b046195-0a9f-4962-9ec3-effa28d9d0ff\u00a0\u00bb header_5_font=\u00a0\u00bb|700|||||||\u00a0\u00bb header_5_text_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb header_5_font_size=\u00a0\u00bb1.5em\u00a0\u00bb header_5_line_height=\u00a0\u00bb1.2em\u00a0\u00bb background_layout=\u00a0\u00bbdark\u00a0\u00bb max_width=\u00a0\u00bb64%\u00a0\u00bb max_width_tablet=\u00a0\u00bb100%\u00a0\u00bb max_width_phone=\u00a0\u00bb100%\u00a0\u00bb max_width_last_edited=\u00a0\u00bbon|tablet\u00a0\u00bb header_5_font_size_tablet=\u00a0\u00bb20px\u00a0\u00bb header_5_font_size_phone=\u00a0\u00bb16px\u00a0\u00bb header_5_font_size_last_edited=\u00a0\u00bbon|desktop\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h5>Collaboration, Transparence, Responsabilit\u00e9, S\u00e9curit\u00e9 et Excellence.<\/h5>\n<p>[\/et_pb_text][et_pb_button button_url=\u00a0\u00bb@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wYWdlIiwic2V0dGluZ3MiOnsicG9zdF9pZCI6IjEwNjAzMSJ9fQ==@\u00a0\u00bb button_text=\u00a0\u00bbPrendre contact\u00a0\u00bb button_alignment=\u00a0\u00bbleft\u00a0\u00bb _builder_version=\u00a0\u00bb4.23.4&Prime; _dynamic_attributes=\u00a0\u00bbbutton_url\u00a0\u00bb _module_preset=\u00a0\u00bb41d703a4-8916-4e7f-8e79-0b35cbcae3f0&Prime; locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_button][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; custom_padding_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb admin_label=\u00a0\u00bbAbout\u00a0\u00bb _builder_version=\u00a0\u00bb4.23.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_enable_color=\u00a0\u00bboff\u00a0\u00bb custom_padding=\u00a0\u00bb0px||0px||true|false\u00a0\u00bb custom_padding_tablet=\u00a0\u00bb15px||15px||true|false\u00a0\u00bb custom_padding_phone=\u00a0\u00bb10px||10px||true|false\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{%22gcid-512fcc6d-fb29-46f9-b53e-275a3a6aef53%22:%91%22background_color%22%93}\u00a0\u00bb][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; admin_label=\u00a0\u00bbFeatures\u00a0\u00bb _builder_version=\u00a0\u00bb4.23.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_padding=\u00a0\u00bb7vw||7vw||true|false\u00a0\u00bb collapsed=\u00a0\u00bbon\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_row _builder_version=\u00a0\u00bb4.23.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.23.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_slider show_pagination=\u00a0\u00bboff\u00a0\u00bb _builder_version=\u00a0\u00bb4.23.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_slide heading=\u00a0\u00bbFlexible\u00a0\u00bb _builder_version=\u00a0\u00bb4.23.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb header_font=\u00a0\u00bbRoboto|700|||||||\u00a0\u00bb header_font_size=\u00a0\u00bb66px\u00a0\u00bb background_color=\u00a0\u00bb#000000&Prime; background_enable_color=\u00a0\u00bbon\u00a0\u00bb header_font_size_tablet=\u00a0\u00bb66px\u00a0\u00bb header_font_size_phone=\u00a0\u00bb66px\u00a0\u00bb header_font_size_last_edited=\u00a0\u00bbon|desktop\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb sticky_transition=\u00a0\u00bbon\u00a0\u00bb][\/et_pb_slide][et_pb_slide heading=\u00a0\u00bbFiable\u00a0\u00bb _builder_version=\u00a0\u00bb4.23.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb header_font=\u00a0\u00bbRoboto|700|||||||\u00a0\u00bb header_font_size=\u00a0\u00bb66px\u00a0\u00bb background_color=\u00a0\u00bb#000000&Prime; background_enable_color=\u00a0\u00bbon\u00a0\u00bb header_font_size_tablet=\u00a0\u00bb66px\u00a0\u00bb header_font_size_phone=\u00a0\u00bb66px\u00a0\u00bb header_font_size_last_edited=\u00a0\u00bbon|desktop\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb sticky_transition=\u00a0\u00bbon\u00a0\u00bb][\/et_pb_slide][et_pb_slide heading=\u00a0\u00bbsoucieux des prix\u00a0\u00bb _builder_version=\u00a0\u00bb4.23.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb header_font=\u00a0\u00bbRoboto|700|||||||\u00a0\u00bb header_font_size=\u00a0\u00bb66px\u00a0\u00bb background_color=\u00a0\u00bb#000000&Prime; background_enable_color=\u00a0\u00bbon\u00a0\u00bb header_font_size_tablet=\u00a0\u00bb66px\u00a0\u00bb header_font_size_phone=\u00a0\u00bb66px\u00a0\u00bb header_font_size_last_edited=\u00a0\u00bbon|desktop\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb sticky_transition=\u00a0\u00bbon\u00a0\u00bb][\/et_pb_slide][et_pb_slide heading=\u00a0\u00bbPonctuel\u00a0\u00bb _builder_version=\u00a0\u00bb4.23.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb header_font=\u00a0\u00bbRoboto|700|||||||\u00a0\u00bb header_font_size=\u00a0\u00bb66px\u00a0\u00bb background_color=\u00a0\u00bb#000000&Prime; background_enable_color=\u00a0\u00bbon\u00a0\u00bb header_font_size_tablet=\u00a0\u00bb66px\u00a0\u00bb header_font_size_phone=\u00a0\u00bb66px\u00a0\u00bb header_font_size_last_edited=\u00a0\u00bbon|desktop\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb sticky_transition=\u00a0\u00bbon\u00a0\u00bb][\/et_pb_slide][\/et_pb_slider][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00a0\u00bb1_3,1_3,1_3&Prime; _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb1_3&Prime; _builder_version=\u00a0\u00bb4.22.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/marsys-trans.com\/wp-content\/uploads\/2023\/12\/nos_valeurs_transparence.jpg\u00a0\u00bb title_text=\u00a0\u00bbnos_valeurs_transparence\u00a0\u00bb _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_margin=\u00a0\u00bb||||false|false\u00a0\u00bb custom_margin_tablet=\u00a0\u00bb||30px||false|false\u00a0\u00bb custom_margin_phone=\u00a0\u00bb||30px||false|false\u00a0\u00bb custom_margin_last_edited=\u00a0\u00bbon|tablet\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{%22gcid-95530a2b-5e91-45c7-8ffb-59bb0a37f154%22:%91%22button_text_color%22,%22border_color_all%22%93,%22gcid-d13dd47d-c04f-4aec-b591-ba88ac7e1568%22:%91%22header_text_color%22%93,%22gcid-c6bf7a23-856a-4cb2-9140-f8fe92a7e2b1%22:%91%22body_text_color%22%93}\u00a0\u00bb][\/et_pb_image][et_pb_cta title=\u00a0\u00bbTransparence\u00a0\u00bb button_url=\u00a0\u00bb#\u00a0\u00bb _builder_version=\u00a0\u00bb4.23.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb header_font=\u00a0\u00bbRufina|700|||||||\u00a0\u00bb header_text_color=\u00a0\u00bbgcid-d13dd47d-c04f-4aec-b591-ba88ac7e1568&Prime; header_font_size=\u00a0\u00bb32px\u00a0\u00bb header_line_height=\u00a0\u00bb1.4em\u00a0\u00bb body_font=\u00a0\u00bbInter||||||||\u00a0\u00bb body_text_color=\u00a0\u00bbgcid-c6bf7a23-856a-4cb2-9140-f8fe92a7e2b1&Prime; body_font_size=\u00a0\u00bb16px\u00a0\u00bb body_line_height=\u00a0\u00bb1.8em\u00a0\u00bb background_color=\u00a0\u00bbRGBA(255,255,255,0)\u00a0\u00bb custom_button=\u00a0\u00bbon\u00a0\u00bb button_text_size=\u00a0\u00bb14px\u00a0\u00bb button_text_color=\u00a0\u00bbgcid-95530a2b-5e91-45c7-8ffb-59bb0a37f154&Prime; button_bg_color=\u00a0\u00bbRGBA(255,255,255,0)\u00a0\u00bb button_border_width=\u00a0\u00bb0px\u00a0\u00bb button_border_radius=\u00a0\u00bb0px\u00a0\u00bb button_font=\u00a0\u00bbInter|700|||||||\u00a0\u00bb button_custom_padding=\u00a0\u00bb|0px||0px|false|true\u00a0\u00bb text_orientation=\u00a0\u00bbleft\u00a0\u00bb custom_margin=\u00a0\u00bb||60px||false|false\u00a0\u00bb custom_margin_tablet=\u00a0\u00bb||30px||false|false\u00a0\u00bb custom_margin_phone=\u00a0\u00bb||30px||false|false\u00a0\u00bb custom_margin_last_edited=\u00a0\u00bbon|tablet\u00a0\u00bb custom_padding=\u00a0\u00bb30px|30px|30px|30px|true|true\u00a0\u00bb custom_padding_tablet=\u00a0\u00bb30px|30px|30px|30px|true|true\u00a0\u00bb custom_padding_phone=\u00a0\u00bb20px|20px|20px|20px|true|true\u00a0\u00bb custom_padding_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb header_font_size_tablet=\u00a0\u00bb20px\u00a0\u00bb header_font_size_phone=\u00a0\u00bb16px\u00a0\u00bb header_font_size_last_edited=\u00a0\u00bbon|desktop\u00a0\u00bb body_font_size_tablet=\u00a0\u00bb15px\u00a0\u00bb body_font_size_phone=\u00a0\u00bb14px\u00a0\u00bb body_font_size_last_edited=\u00a0\u00bbon|desktop\u00a0\u00bb border_width_all=\u00a0\u00bb2px\u00a0\u00bb border_color_all=\u00a0\u00bb#3871B5&Prime; global_colors_info=\u00a0\u00bb{%22gcid-95530a2b-5e91-45c7-8ffb-59bb0a37f154%22:%91%22button_text_color%22%93,%22gcid-d13dd47d-c04f-4aec-b591-ba88ac7e1568%22:%91%22header_text_color%22%93,%22gcid-c6bf7a23-856a-4cb2-9140-f8fe92a7e2b1%22:%91%22body_text_color%22%93}\u00a0\u00bb]<\/p>\n<p>La cl\u00e9 de notre collaboration avec nos partenaires et clients car elle permet de cr\u00e9er et de maintenir une relation durable.<\/p>\n<p>[\/et_pb_cta][et_pb_image src=\u00a0\u00bbhttps:\/\/marsys-trans.com\/wp-content\/uploads\/2023\/12\/nos_valeurs_securite.jpg\u00a0\u00bb title_text=\u00a0\u00bbnos_valeurs_securite\u00a0\u00bb _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][et_pb_cta title=\u00a0\u00bbSecurit\u00e9\u00a0\u00bb button_url=\u00a0\u00bb#\u00a0\u00bb _builder_version=\u00a0\u00bb4.23.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb header_font=\u00a0\u00bbRufina|700|||||||\u00a0\u00bb header_text_color=\u00a0\u00bbgcid-d13dd47d-c04f-4aec-b591-ba88ac7e1568&Prime; header_font_size=\u00a0\u00bb32px\u00a0\u00bb header_line_height=\u00a0\u00bb1.4em\u00a0\u00bb body_font=\u00a0\u00bbInter||||||||\u00a0\u00bb body_text_color=\u00a0\u00bbgcid-c6bf7a23-856a-4cb2-9140-f8fe92a7e2b1&Prime; body_font_size=\u00a0\u00bb16px\u00a0\u00bb body_line_height=\u00a0\u00bb1.8em\u00a0\u00bb background_color=\u00a0\u00bbRGBA(255,255,255,0)\u00a0\u00bb custom_button=\u00a0\u00bbon\u00a0\u00bb button_text_size=\u00a0\u00bb14px\u00a0\u00bb button_text_color=\u00a0\u00bbgcid-95530a2b-5e91-45c7-8ffb-59bb0a37f154&Prime; button_bg_color=\u00a0\u00bbRGBA(255,255,255,0)\u00a0\u00bb button_border_width=\u00a0\u00bb0px\u00a0\u00bb button_border_radius=\u00a0\u00bb0px\u00a0\u00bb button_font=\u00a0\u00bbInter|700|||||||\u00a0\u00bb button_custom_padding=\u00a0\u00bb|0px||0px|false|true\u00a0\u00bb text_orientation=\u00a0\u00bbleft\u00a0\u00bb custom_margin=\u00a0\u00bb||60px||false|false\u00a0\u00bb custom_margin_tablet=\u00a0\u00bb||30px||false|false\u00a0\u00bb custom_margin_phone=\u00a0\u00bb||30px||false|false\u00a0\u00bb custom_margin_last_edited=\u00a0\u00bbon|tablet\u00a0\u00bb custom_padding=\u00a0\u00bb30px|30px|30px|30px|true|true\u00a0\u00bb custom_padding_tablet=\u00a0\u00bb30px|30px|30px|30px|true|true\u00a0\u00bb custom_padding_phone=\u00a0\u00bb20px|20px|20px|20px|true|true\u00a0\u00bb custom_padding_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb header_font_size_tablet=\u00a0\u00bb20px\u00a0\u00bb header_font_size_phone=\u00a0\u00bb16px\u00a0\u00bb header_font_size_last_edited=\u00a0\u00bbon|desktop\u00a0\u00bb body_font_size_tablet=\u00a0\u00bb15px\u00a0\u00bb body_font_size_phone=\u00a0\u00bb14px\u00a0\u00bb body_font_size_last_edited=\u00a0\u00bbon|desktop\u00a0\u00bb border_width_all=\u00a0\u00bb2px\u00a0\u00bb border_color_all=\u00a0\u00bb#3871B5&Prime; global_colors_info=\u00a0\u00bb{%22gcid-95530a2b-5e91-45c7-8ffb-59bb0a37f154%22:%91%22button_text_color%22%93,%22gcid-d13dd47d-c04f-4aec-b591-ba88ac7e1568%22:%91%22header_text_color%22%93,%22gcid-c6bf7a23-856a-4cb2-9140-f8fe92a7e2b1%22:%91%22body_text_color%22%93}\u00a0\u00bb]<\/p>\n<p>Pi\u00e8ce maitresse de notre c\u0153ur de m\u00e9tier. Assurer la s\u00e9curit\u00e9 de nos employ\u00e9s et des biens qui nous sont confi\u00e9s est primordiale.<\/p>\n<p>[\/et_pb_cta][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_3&Prime; _builder_version=\u00a0\u00bb4.22.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_cta title=\u00a0\u00bbCollaboration\u00a0\u00bb button_url=\u00a0\u00bb#\u00a0\u00bb _builder_version=\u00a0\u00bb4.23.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb header_font=\u00a0\u00bbRufina|700|||||||\u00a0\u00bb header_text_color=\u00a0\u00bbgcid-d13dd47d-c04f-4aec-b591-ba88ac7e1568&Prime; header_font_size=\u00a0\u00bb32px\u00a0\u00bb header_line_height=\u00a0\u00bb1.4em\u00a0\u00bb body_font=\u00a0\u00bbInter||||||||\u00a0\u00bb body_text_color=\u00a0\u00bbgcid-c6bf7a23-856a-4cb2-9140-f8fe92a7e2b1&Prime; body_font_size=\u00a0\u00bb16px\u00a0\u00bb body_line_height=\u00a0\u00bb1.8em\u00a0\u00bb background_color=\u00a0\u00bbRGBA(255,255,255,0)\u00a0\u00bb custom_button=\u00a0\u00bbon\u00a0\u00bb button_text_size=\u00a0\u00bb14px\u00a0\u00bb button_text_color=\u00a0\u00bbgcid-95530a2b-5e91-45c7-8ffb-59bb0a37f154&Prime; button_bg_color=\u00a0\u00bbRGBA(255,255,255,0)\u00a0\u00bb button_border_width=\u00a0\u00bb0px\u00a0\u00bb button_border_radius=\u00a0\u00bb0px\u00a0\u00bb button_font=\u00a0\u00bbInter|700|||||||\u00a0\u00bb button_custom_padding=\u00a0\u00bb|0px||0px|false|true\u00a0\u00bb text_orientation=\u00a0\u00bbleft\u00a0\u00bb custom_margin=\u00a0\u00bb||60px||false|false\u00a0\u00bb custom_margin_tablet=\u00a0\u00bb||30px||false|false\u00a0\u00bb custom_margin_phone=\u00a0\u00bb||30px||false|false\u00a0\u00bb custom_margin_last_edited=\u00a0\u00bbon|tablet\u00a0\u00bb custom_padding=\u00a0\u00bb30px|30px|30px|30px|true|true\u00a0\u00bb custom_padding_tablet=\u00a0\u00bb30px|30px|30px|30px|true|true\u00a0\u00bb custom_padding_phone=\u00a0\u00bb20px|20px|20px|20px|true|true\u00a0\u00bb custom_padding_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb header_font_size_tablet=\u00a0\u00bb20px\u00a0\u00bb header_font_size_phone=\u00a0\u00bb16px\u00a0\u00bb header_font_size_last_edited=\u00a0\u00bbon|desktop\u00a0\u00bb body_font_size_tablet=\u00a0\u00bb15px\u00a0\u00bb body_font_size_phone=\u00a0\u00bb14px\u00a0\u00bb body_font_size_last_edited=\u00a0\u00bbon|desktop\u00a0\u00bb border_width_all=\u00a0\u00bb2px\u00a0\u00bb border_color_all=\u00a0\u00bb#3871B5&Prime; global_colors_info=\u00a0\u00bb{%22gcid-95530a2b-5e91-45c7-8ffb-59bb0a37f154%22:%91%22button_text_color%22%93,%22gcid-d13dd47d-c04f-4aec-b591-ba88ac7e1568%22:%91%22header_text_color%22%93,%22gcid-c6bf7a23-856a-4cb2-9140-f8fe92a7e2b1%22:%91%22body_text_color%22%93}\u00a0\u00bb]<\/p>\n<p>Avec nos diff\u00e9rents partenaires et clients afin de r\u00e9pondre \u00e0 leurs attentes actuelles et futures.<\/p>\n<p>[\/et_pb_cta][et_pb_image src=\u00a0\u00bbhttps:\/\/marsys-trans.com\/wp-content\/uploads\/2023\/12\/nos_valeurs_collaboration_V.jpg\u00a0\u00bb title_text=\u00a0\u00bbnos_valeurs_collaboration_V\u00a0\u00bb _builder_version=\u00a0\u00bb4.23.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_margin=\u00a0\u00bb||53px||false|false\u00a0\u00bb custom_margin_tablet=\u00a0\u00bb||30px||false|false\u00a0\u00bb custom_margin_phone=\u00a0\u00bb||30px||false|false\u00a0\u00bb custom_margin_last_edited=\u00a0\u00bbon|tablet\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{%22gcid-95530a2b-5e91-45c7-8ffb-59bb0a37f154%22:%91%22button_text_color%22,%22border_color_all%22%93,%22gcid-d13dd47d-c04f-4aec-b591-ba88ac7e1568%22:%91%22header_text_color%22%93,%22gcid-c6bf7a23-856a-4cb2-9140-f8fe92a7e2b1%22:%91%22body_text_color%22%93}\u00a0\u00bb][\/et_pb_image][et_pb_cta button_url=\u00a0\u00bb#\u00a0\u00bb _builder_version=\u00a0\u00bb4.23.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb header_font=\u00a0\u00bbRufina|700|||||||\u00a0\u00bb header_text_color=\u00a0\u00bbgcid-d13dd47d-c04f-4aec-b591-ba88ac7e1568&Prime; header_font_size=\u00a0\u00bb32px\u00a0\u00bb header_line_height=\u00a0\u00bb1.4em\u00a0\u00bb body_font=\u00a0\u00bbInter||||||||\u00a0\u00bb body_text_color=\u00a0\u00bbgcid-c6bf7a23-856a-4cb2-9140-f8fe92a7e2b1&Prime; body_font_size=\u00a0\u00bb16px\u00a0\u00bb body_line_height=\u00a0\u00bb1.8em\u00a0\u00bb background_color=\u00a0\u00bbRGBA(255,255,255,0)\u00a0\u00bb custom_button=\u00a0\u00bbon\u00a0\u00bb button_text_size=\u00a0\u00bb14px\u00a0\u00bb button_text_color=\u00a0\u00bbgcid-95530a2b-5e91-45c7-8ffb-59bb0a37f154&Prime; button_bg_color=\u00a0\u00bbRGBA(255,255,255,0)\u00a0\u00bb button_border_width=\u00a0\u00bb0px\u00a0\u00bb button_border_radius=\u00a0\u00bb0px\u00a0\u00bb button_font=\u00a0\u00bbInter|700|||||||\u00a0\u00bb button_custom_padding=\u00a0\u00bb|0px||0px|false|true\u00a0\u00bb text_orientation=\u00a0\u00bbjustified\u00a0\u00bb custom_margin=\u00a0\u00bb||60px||false|false\u00a0\u00bb custom_margin_tablet=\u00a0\u00bb||30px||false|false\u00a0\u00bb custom_margin_phone=\u00a0\u00bb||30px||false|false\u00a0\u00bb custom_margin_last_edited=\u00a0\u00bbon|tablet\u00a0\u00bb custom_padding=\u00a0\u00bb0px|0px|2px|0px|false|true\u00a0\u00bb custom_padding_tablet=\u00a0\u00bb30px|30px|30px|30px|true|true\u00a0\u00bb custom_padding_phone=\u00a0\u00bb20px|20px|20px|20px|true|true\u00a0\u00bb custom_padding_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb header_font_size_tablet=\u00a0\u00bb20px\u00a0\u00bb header_font_size_phone=\u00a0\u00bb16px\u00a0\u00bb header_font_size_last_edited=\u00a0\u00bbon|desktop\u00a0\u00bb body_font_size_tablet=\u00a0\u00bb15px\u00a0\u00bb body_font_size_phone=\u00a0\u00bb14px\u00a0\u00bb body_font_size_last_edited=\u00a0\u00bbon|desktop\u00a0\u00bb border_color_all=\u00a0\u00bbgcid-512fcc6d-fb29-46f9-b53e-275a3a6aef53&Prime; global_colors_info=\u00a0\u00bb{%22gcid-95530a2b-5e91-45c7-8ffb-59bb0a37f154%22:%91%22button_text_color%22%93,%22gcid-d13dd47d-c04f-4aec-b591-ba88ac7e1568%22:%91%22header_text_color%22%93,%22gcid-c6bf7a23-856a-4cb2-9140-f8fe92a7e2b1%22:%91%22body_text_color%22%93,%22gcid-512fcc6d-fb29-46f9-b53e-275a3a6aef53%22:%91%22border_color_all%22%93}\u00a0\u00bb]<\/p>\n<p>Notre travail est de toujours offrir un service fiable \u00e0 des prix \u00e9quitables. Notre objectif est de satisfaire nos clients et ainsi de les fid\u00e9liser sur le long terme !<br \/>Notre profil de performance \u00e9volue avec des exigences en constante \u00e9volution. Cela signifie que nous disposons \u00e9galement de la meilleure solution pour le march\u00e9 logistique de demain.<\/p>\n<p>[\/et_pb_cta][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_3&Prime; _builder_version=\u00a0\u00bb4.22.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/marsys-trans.com\/wp-content\/uploads\/2023\/12\/nos_valeurs_responsabilite.jpg\u00a0\u00bb title_text=\u00a0\u00bbnos_valeurs_responsabilite\u00a0\u00bb _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][et_pb_cta title=\u00a0\u00bbR\u00e9sponsabilit\u00e9\u00a0\u00bb button_url=\u00a0\u00bb#\u00a0\u00bb _builder_version=\u00a0\u00bb4.23.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb header_font=\u00a0\u00bbRufina|700|||||||\u00a0\u00bb header_text_color=\u00a0\u00bbgcid-d13dd47d-c04f-4aec-b591-ba88ac7e1568&Prime; header_font_size=\u00a0\u00bb32px\u00a0\u00bb header_line_height=\u00a0\u00bb1.4em\u00a0\u00bb body_font=\u00a0\u00bbInter||||||||\u00a0\u00bb body_text_color=\u00a0\u00bbgcid-c6bf7a23-856a-4cb2-9140-f8fe92a7e2b1&Prime; body_font_size=\u00a0\u00bb16px\u00a0\u00bb body_line_height=\u00a0\u00bb1.8em\u00a0\u00bb background_color=\u00a0\u00bbRGBA(255,255,255,0)\u00a0\u00bb custom_button=\u00a0\u00bbon\u00a0\u00bb button_text_size=\u00a0\u00bb14px\u00a0\u00bb button_text_color=\u00a0\u00bbgcid-95530a2b-5e91-45c7-8ffb-59bb0a37f154&Prime; button_bg_color=\u00a0\u00bbRGBA(255,255,255,0)\u00a0\u00bb button_border_width=\u00a0\u00bb0px\u00a0\u00bb button_border_radius=\u00a0\u00bb0px\u00a0\u00bb button_font=\u00a0\u00bbInter|700|||||||\u00a0\u00bb button_custom_padding=\u00a0\u00bb|0px||0px|false|true\u00a0\u00bb text_orientation=\u00a0\u00bbleft\u00a0\u00bb custom_margin=\u00a0\u00bb||60px||false|false\u00a0\u00bb custom_margin_tablet=\u00a0\u00bb||30px||false|false\u00a0\u00bb custom_margin_phone=\u00a0\u00bb||30px||false|false\u00a0\u00bb custom_margin_last_edited=\u00a0\u00bbon|tablet\u00a0\u00bb custom_padding=\u00a0\u00bb30px|30px|30px|30px|true|true\u00a0\u00bb custom_padding_tablet=\u00a0\u00bb30px|30px|30px|30px|true|true\u00a0\u00bb custom_padding_phone=\u00a0\u00bb20px|20px|20px|20px|true|true\u00a0\u00bb custom_padding_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb header_font_size_tablet=\u00a0\u00bb20px\u00a0\u00bb header_font_size_phone=\u00a0\u00bb16px\u00a0\u00bb header_font_size_last_edited=\u00a0\u00bbon|desktop\u00a0\u00bb body_font_size_tablet=\u00a0\u00bb15px\u00a0\u00bb body_font_size_phone=\u00a0\u00bb14px\u00a0\u00bb body_font_size_last_edited=\u00a0\u00bbon|desktop\u00a0\u00bb border_width_all=\u00a0\u00bb2px\u00a0\u00bb border_color_all=\u00a0\u00bb#3871B5&Prime; locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{%22gcid-95530a2b-5e91-45c7-8ffb-59bb0a37f154%22:%91%22button_text_color%22,%22button_text_color%22,%22button_text_color%22,%22button_text_color%22%93,%22gcid-d13dd47d-c04f-4aec-b591-ba88ac7e1568%22:%91%22header_text_color%22,%22header_text_color%22,%22header_text_color%22,%22header_text_color%22%93,%22gcid-c6bf7a23-856a-4cb2-9140-f8fe92a7e2b1%22:%91%22body_text_color%22,%22body_text_color%22,%22body_text_color%22,%22body_text_color%22%93}\u00a0\u00bb]<\/p>\n<p>S\u2019engager et honorer ses engagements est un gage de p\u00e9rennit\u00e9 et de cr\u00e9dibilit\u00e9 de nos services.<\/p>\n<p>[\/et_pb_cta][et_pb_image src=\u00a0\u00bbhttps:\/\/marsys-trans.com\/wp-content\/uploads\/2023\/12\/nos_valeurs_Excellence.jpg\u00a0\u00bb title_text=\u00a0\u00bbnos_valeurs_Excellence\u00a0\u00bb _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][et_pb_cta title=\u00a0\u00bbL&rsquo;excellence\u00a0\u00bb button_url=\u00a0\u00bb#\u00a0\u00bb _builder_version=\u00a0\u00bb4.23.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb header_font=\u00a0\u00bbRufina|700|||||||\u00a0\u00bb header_text_color=\u00a0\u00bbgcid-d13dd47d-c04f-4aec-b591-ba88ac7e1568&Prime; header_font_size=\u00a0\u00bb32px\u00a0\u00bb header_line_height=\u00a0\u00bb1.4em\u00a0\u00bb body_font=\u00a0\u00bbInter||||||||\u00a0\u00bb body_text_color=\u00a0\u00bbgcid-c6bf7a23-856a-4cb2-9140-f8fe92a7e2b1&Prime; body_font_size=\u00a0\u00bb16px\u00a0\u00bb body_line_height=\u00a0\u00bb1.8em\u00a0\u00bb background_color=\u00a0\u00bbRGBA(255,255,255,0)\u00a0\u00bb custom_button=\u00a0\u00bbon\u00a0\u00bb button_text_size=\u00a0\u00bb14px\u00a0\u00bb button_text_color=\u00a0\u00bbgcid-95530a2b-5e91-45c7-8ffb-59bb0a37f154&Prime; button_bg_color=\u00a0\u00bbRGBA(255,255,255,0)\u00a0\u00bb button_border_width=\u00a0\u00bb0px\u00a0\u00bb button_border_radius=\u00a0\u00bb0px\u00a0\u00bb button_font=\u00a0\u00bbInter|700|||||||\u00a0\u00bb button_custom_padding=\u00a0\u00bb|0px||0px|false|true\u00a0\u00bb text_orientation=\u00a0\u00bbleft\u00a0\u00bb custom_margin=\u00a0\u00bb||60px||false|false\u00a0\u00bb custom_margin_tablet=\u00a0\u00bb||30px||false|false\u00a0\u00bb custom_margin_phone=\u00a0\u00bb||30px||false|false\u00a0\u00bb custom_margin_last_edited=\u00a0\u00bbon|tablet\u00a0\u00bb custom_padding=\u00a0\u00bb30px|30px|30px|30px|true|true\u00a0\u00bb custom_padding_tablet=\u00a0\u00bb30px|30px|30px|30px|true|true\u00a0\u00bb custom_padding_phone=\u00a0\u00bb20px|20px|20px|20px|true|true\u00a0\u00bb custom_padding_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb header_font_size_tablet=\u00a0\u00bb20px\u00a0\u00bb header_font_size_phone=\u00a0\u00bb16px\u00a0\u00bb header_font_size_last_edited=\u00a0\u00bbon|desktop\u00a0\u00bb body_font_size_tablet=\u00a0\u00bb15px\u00a0\u00bb body_font_size_phone=\u00a0\u00bb14px\u00a0\u00bb body_font_size_last_edited=\u00a0\u00bbon|desktop\u00a0\u00bb border_width_all=\u00a0\u00bb2px\u00a0\u00bb border_color_all=\u00a0\u00bb#3871B5&Prime; global_colors_info=\u00a0\u00bb{%22gcid-95530a2b-5e91-45c7-8ffb-59bb0a37f154%22:%91%22button_text_color%22%93,%22gcid-d13dd47d-c04f-4aec-b591-ba88ac7e1568%22:%91%22header_text_color%22%93,%22gcid-c6bf7a23-856a-4cb2-9140-f8fe92a7e2b1%22:%91%22body_text_color%22%93}\u00a0\u00bb]<\/p>\n<p>La recherche permanente de solutions efficientes guide l\u2019ensemble de nos collaborateurs dans une logique d\u2019am\u00e9lioration continue.<\/p>\n<p>[\/et_pb_cta][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; custom_padding_last_edited=\u00a0\u00bbon|tablet\u00a0\u00bb disabled_on=\u00a0\u00bboff|off|off\u00a0\u00bb admin_label=\u00a0\u00bbFooter\u00a0\u00bb _builder_version=\u00a0\u00bb4.23.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_color=\u00a0\u00bbgcid-bb0ed12f-ade3-45a9-94a8-c2773fdbea01&Prime; use_background_color_gradient=\u00a0\u00bbon\u00a0\u00bb background_color_gradient_direction=\u00a0\u00bb90deg\u00a0\u00bb background_color_gradient_stops=\u00a0\u00bbgcid-bb0ed12f-ade3-45a9-94a8-c2773fdbea01 58%|#28292d 82%\u00a0\u00bb background_color_gradient_overlays_image=\u00a0\u00bbon\u00a0\u00bb background_color_gradient_start=\u00a0\u00bb#2f5349&Prime; background_color_gradient_start_position=\u00a0\u00bb56%\u00a0\u00bb background_color_gradient_end=\u00a0\u00bbrgba(0,0,0,0)\u00a0\u00bb background_color_gradient_end_position=\u00a0\u00bb56%\u00a0\u00bb background_image=\u00a0\u00bbhttps:\/\/marsys-trans.com\/wp-content\/uploads\/2023\/12\/Truck-Footer.jpeg\u00a0\u00bb background_position=\u00a0\u00bbtop_right\u00a0\u00bb background_horizontal_offset=\u00a0\u00bb2%\u00a0\u00bb custom_padding=\u00a0\u00bb0px|0px|3px||false|false\u00a0\u00bb custom_padding_tablet=\u00a0\u00bb0px||100px||false|false\u00a0\u00bb custom_padding_phone=\u00a0\u00bb0px||100px||false|false\u00a0\u00bb top_divider_style_tablet=\u00a0\u00bb\u00a0\u00bb top_divider_style_phone=\u00a0\u00bb\u00a0\u00bb top_divider_style_last_edited=\u00a0\u00bbon|tablet\u00a0\u00bb bottom_divider_style=\u00a0\u00bbasymmetric2&Prime; bottom_divider_color=\u00a0\u00bbgcid-512fcc6d-fb29-46f9-b53e-275a3a6aef53&Prime; bottom_divider_style_tablet=\u00a0\u00bbnone\u00a0\u00bb bottom_divider_style_phone=\u00a0\u00bbnone\u00a0\u00bb bottom_divider_style_last_edited=\u00a0\u00bbon|desktop\u00a0\u00bb background_last_edited=\u00a0\u00bbon|desktop\u00a0\u00bb use_background_color_gradient_tablet=\u00a0\u00bbon\u00a0\u00bb background_color_gradient_stops_tablet=\u00a0\u00bbrgba(0,0,0,0) 100%|gcid-bb0ed12f-ade3-45a9-94a8-c2773fdbea01 100%\u00a0\u00bb background_color_gradient_start_position_tablet=\u00a0\u00bb100%\u00a0\u00bb background_color_gradient_end_position_tablet=\u00a0\u00bb100%\u00a0\u00bb background_enable_image_tablet=\u00a0\u00bboff\u00a0\u00bb global_module=\u00a0\u00bb106098&Prime; saved_tabs=\u00a0\u00bball\u00a0\u00bb global_colors_info=\u00a0\u00bb{%22gcid-512fcc6d-fb29-46f9-b53e-275a3a6aef53%22:%91%22bottom_divider_color%22%93}\u00a0\u00bb][et_pb_row column_structure=\u00a0\u00bb1_2,1_2&Prime; make_equal=\u00a0\u00bbon\u00a0\u00bb _builder_version=\u00a0\u00bb4.23.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_color=\u00a0\u00bb#28292D\u00a0\u00bb width=\u00a0\u00bb79.4%\u00a0\u00bb max_width=\u00a0\u00bb1674px\u00a0\u00bb min_height=\u00a0\u00bb508.8px\u00a0\u00bb custom_margin=\u00a0\u00bb|151px|-4px|auto||\u00a0\u00bb custom_padding=\u00a0\u00bb0px||0px||true|false\u00a0\u00bb border_radii=\u00a0\u00bboff|||30px|\u00a0\u00bb border_radii_tablet=\u00a0\u00bboff|||0px|\u00a0\u00bb border_radii_phone=\u00a0\u00bb\u00a0\u00bb border_radii_last_edited=\u00a0\u00bbon|desktop\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_color=\u00a0\u00bbgcid-bb0ed12f-ade3-45a9-94a8-c2773fdbea01&Prime; custom_padding=\u00a0\u00bb100px|60px|30px||false|false\u00a0\u00bb custom_padding_tablet=\u00a0\u00bb60px|0px|60px||true|false\u00a0\u00bb custom_padding_phone=\u00a0\u00bb60px|0px|60px||true|false\u00a0\u00bb custom_padding_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb global_colors_info=\u00a0\u00bb{%22gcid-bb0ed12f-ade3-45a9-94a8-c2773fdbea01%22:%91%22background_color%22%93}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.23.4&Prime; _module_preset=\u00a0\u00bb3a5fa9a7-7987-4564-89a5-37b87a5b6ad8&Prime; header_font=\u00a0\u00bb||||||||\u00a0\u00bb header_3_font=\u00a0\u00bbUrbanist|700|||||||\u00a0\u00bb header_3_text_color=\u00a0\u00bb#000000&Prime; header_3_font_size=\u00a0\u00bb32px\u00a0\u00bb header_3_line_height=\u00a0\u00bb1.4em\u00a0\u00bb text_orientation=\u00a0\u00bbcenter\u00a0\u00bb background_layout=\u00a0\u00bbdark\u00a0\u00bb custom_margin=\u00a0\u00bb70px||10px||false|false\u00a0\u00bb header_3_font_size_tablet=\u00a0\u00bb3em\u00a0\u00bb header_3_font_size_phone=\u00a0\u00bb2em\u00a0\u00bb header_3_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h3>Confier nous votre besoin<\/h3>\n<p>[\/et_pb_text][et_pb_button button_url=\u00a0\u00bb@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wYWdlIiwic2V0dGluZ3MiOnsicG9zdF9pZCI6IjEwNjAzMSJ9fQ==@\u00a0\u00bb button_text=\u00a0\u00bbDemander un Devis\u00a0\u00bb button_alignment=\u00a0\u00bbcenter\u00a0\u00bb button_alignment_tablet=\u00a0\u00bb\u00a0\u00bb button_alignment_phone=\u00a0\u00bbcenter\u00a0\u00bb button_alignment_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb disabled_on=\u00a0\u00bboff|off|off\u00a0\u00bb _builder_version=\u00a0\u00bb4.23.4&Prime; _dynamic_attributes=\u00a0\u00bbbutton_url\u00a0\u00bb _module_preset=\u00a0\u00bb792e8a4c-21ad-45f0-9c1e-f26122ab1b0c\u00a0\u00bb button_text_size=\u00a0\u00bb16px\u00a0\u00bb button_text_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb button_bg_color=\u00a0\u00bb#27292d\u00a0\u00bb button_border_radius=\u00a0\u00bb0px\u00a0\u00bb button_font=\u00a0\u00bbRoboto|||on|||||\u00a0\u00bb custom_margin=\u00a0\u00bb35px||57px||false|false\u00a0\u00bb custom_padding=\u00a0\u00bb15px|24px|15px|24px|true|true\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_button][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_padding=\u00a0\u00bb100px|60px|30px||false|false\u00a0\u00bb custom_padding_tablet=\u00a0\u00bb40px|30px|40px|30px|true|true\u00a0\u00bb custom_padding_phone=\u00a0\u00bb|20px||20px|false|true\u00a0\u00bb custom_padding_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bb4deaa1a6-d0cd-49d0-ada3-8dc22addd086&Prime; header_4_font=\u00a0\u00bbUrbanist|800||on|||||\u00a0\u00bb header_4_text_color=\u00a0\u00bbgcid-bb0ed12f-ade3-45a9-94a8-c2773fdbea01&Prime; header_4_font_size=\u00a0\u00bb16px\u00a0\u00bb header_4_letter_spacing=\u00a0\u00bb0.4em\u00a0\u00bb header_4_line_height=\u00a0\u00bb1.4em\u00a0\u00bb custom_margin=\u00a0\u00bb||0px||false|false\u00a0\u00bb header_4_font_size_tablet=\u00a0\u00bb14px\u00a0\u00bb header_4_font_size_phone=\u00a0\u00bb12px\u00a0\u00bb header_4_font_size_last_edited=\u00a0\u00bbon|desktop\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{%22gcid-bb0ed12f-ade3-45a9-94a8-c2773fdbea01%22:%91%22header_4_text_color%22%93}\u00a0\u00bb]<\/p>\n<h4>Appelez-nous<\/h4>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.23.4&Prime; _module_preset=\u00a0\u00bb7c6f8f23-f33e-40b2-bf4c-26f4c5032887&Prime; text_font=\u00a0\u00bbUrbanist|700|||||||\u00a0\u00bb text_font_size=\u00a0\u00bb40px\u00a0\u00bb text_line_height=\u00a0\u00bb1.4em\u00a0\u00bb link_text_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb custom_margin=\u00a0\u00bb||30px||false|false\u00a0\u00bb text_font_size_tablet=\u00a0\u00bb32px\u00a0\u00bb text_font_size_phone=\u00a0\u00bb20px\u00a0\u00bb text_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p><a href=\"#\">+212 (0) 5 22 24 21 14<\/a><\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bb3a5fa9a7-7987-4564-89a5-37b87a5b6ad8&Prime; header_font=\u00a0\u00bb||||||||\u00a0\u00bb header_3_font=\u00a0\u00bbUrbanist|700|||||||\u00a0\u00bb header_3_text_color=\u00a0\u00bbgcid-bb0ed12f-ade3-45a9-94a8-c2773fdbea01&Prime; header_3_font_size=\u00a0\u00bb32px\u00a0\u00bb header_3_line_height=\u00a0\u00bb1.4em\u00a0\u00bb custom_margin=\u00a0\u00bb||0px||false|false\u00a0\u00bb custom_margin_tablet=\u00a0\u00bb50px||10px||false|false\u00a0\u00bb custom_margin_phone=\u00a0\u00bb40px||||false|false\u00a0\u00bb custom_margin_last_edited=\u00a0\u00bboff|desktop\u00a0\u00bb header_3_font_size_tablet=\u00a0\u00bb20px\u00a0\u00bb header_3_font_size_phone=\u00a0\u00bb16px\u00a0\u00bb header_3_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{%22gcid-bb0ed12f-ade3-45a9-94a8-c2773fdbea01%22:%91%22header_3_text_color%22%93}\u00a0\u00bb]<\/p>\n<h3>Newsletter<\/h3>\n<p>[\/et_pb_text][et_pb_signup mailchimp_list=\u00a0\u00bbelegantthemestest|1ea2bbd026&Prime; first_name_field=\u00a0\u00bboff\u00a0\u00bb last_name_field=\u00a0\u00bboff\u00a0\u00bb button_text=\u00a0\u00bbJe m&rsquo;abonne\u00a0\u00bb _builder_version=\u00a0\u00bb4.23.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb form_field_background_color=\u00a0\u00bbRGBA(0,0,0,0)\u00a0\u00bb form_field_text_color=\u00a0\u00bbrgba(255,255,255,0.5)\u00a0\u00bb use_background_color=\u00a0\u00bboff\u00a0\u00bb custom_button=\u00a0\u00bbon\u00a0\u00bb button_text_size=\u00a0\u00bb14px\u00a0\u00bb button_text_color=\u00a0\u00bb#000000&Prime; button_bg_color=\u00a0\u00bbgcid-bb0ed12f-ade3-45a9-94a8-c2773fdbea01&Prime; button_border_width=\u00a0\u00bb0px\u00a0\u00bb button_border_radius=\u00a0\u00bb0px\u00a0\u00bb button_letter_spacing=\u00a0\u00bb0.2em\u00a0\u00bb button_font=\u00a0\u00bbRoboto|||on|||||\u00a0\u00bb button_custom_padding=\u00a0\u00bb16px||16px||true|false\u00a0\u00bb button_custom_padding_tablet=\u00a0\u00bb15px||15px||true|false\u00a0\u00bb button_custom_padding_phone=\u00a0\u00bb14px||14px||true|false\u00a0\u00bb button_custom_padding_last_edited=\u00a0\u00bbon|tablet\u00a0\u00bb border_radii_fields=\u00a0\u00bbon|0px|0px|0px|0px\u00a0\u00bb border_width_all_fields=\u00a0\u00bb2px\u00a0\u00bb border_color_all_fields=\u00a0\u00bbrgba(255,255,255,0.1)\u00a0\u00bb global_colors_info=\u00a0\u00bb{%22gcid-bb0ed12f-ade3-45a9-94a8-c2773fdbea01%22:%91%22button_bg_color%22%93}\u00a0\u00bb button_bg_color__hover_enabled=\u00a0\u00bbon|hover\u00a0\u00bb button_bg_color__hover=\u00a0\u00bb#7C8B56&Prime; button_bg_enable_color__hover=\u00a0\u00bbon\u00a0\u00bb][\/et_pb_signup][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nos Valeurs,Collaboration, Transparence, Responsabilit\u00e9, S\u00e9curit\u00e9 et Excellence.La cl\u00e9 de notre collaboration avec nos partenaires et clients car elle permet de cr\u00e9er et de maintenir une relation durable.Pi\u00e8ce maitresse de notre c\u0153ur de m\u00e9tier. Assurer la s\u00e9curit\u00e9 de nos employ\u00e9s et des biens qui nous sont confi\u00e9s est primordiale.Avec nos diff\u00e9rents partenaires et clients afin de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"class_list":["post-234165","page","type-page","status-publish","hentry"],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/marsys-trans.com\/index.php\/wp-json\/wp\/v2\/pages\/234165","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/marsys-trans.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/marsys-trans.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/marsys-trans.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/marsys-trans.com\/index.php\/wp-json\/wp\/v2\/comments?post=234165"}],"version-history":[{"count":41,"href":"https:\/\/marsys-trans.com\/index.php\/wp-json\/wp\/v2\/pages\/234165\/revisions"}],"predecessor-version":[{"id":235288,"href":"https:\/\/marsys-trans.com\/index.php\/wp-json\/wp\/v2\/pages\/234165\/revisions\/235288"}],"wp:attachment":[{"href":"https:\/\/marsys-trans.com\/index.php\/wp-json\/wp\/v2\/media?parent=234165"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}